{"id":1968,"date":"2019-01-17T12:58:58","date_gmt":"2019-01-17T04:58:58","guid":{"rendered":"https:\/\/www.cityhub.com.sg\/centre\/prospect-rd\/"},"modified":"2019-01-17T13:23:27","modified_gmt":"2019-01-17T05:23:27","slug":"prospect-rd","status":"publish","type":"centre","link":"https:\/\/www.cityhub.com.sg\/ko\/centre\/prospect-rd\/","title":{"rendered":"Prospect Rd"},"content":{"rendered":"<p><strong>Services include:<\/strong><\/p>\n<ul>\n<li>Free boardroom use<\/li>\n<li>Free internet, printing &amp; scanning<\/li>\n<li>Free mail slot &amp; handling<\/li>\n<li>Free access 24 hour 7 days per week<\/li>\n<li>Free kitchen facilities<\/li>\n<li>Fully furnished offices<\/li>\n<li>Heart of Prospect<\/li>\n<li>Great coffee downstairs with delivery!<\/li>\n<\/ul>\n<div class=\"et_pb_module et_pb_text et_pb_text_0 et_pb_bg_layout_light et_pb_text_align_left\">\n<div class=\"et_pb_text_inner\">\n<p><strong>This office facility is close to:<\/strong><\/p>\n<ul>\n<li>All public transport<\/li>\n<li>5 mins to the city<\/li>\n<li>Cotto, Muratti, Cibo and many more cafes<\/li>\n<li>Nova Cinema complex<\/li>\n<li>Prospect council<\/li>\n<li>Adelaide Oval<\/li>\n<li>North Adelaide retail strip<\/li>\n<\/ul>\n<\/div>\n<\/div>\n","protected":false},"featured_media":1962,"template":"","class_list":{"0":"post-1968","1":"centre","2":"type-centre","3":"status-publish","4":"has-post-thumbnail","6":"entry"},"acf":[],"_links":{"self":[{"href":"https:\/\/www.cityhub.com.sg\/ko\/wp-json\/wp\/v2\/centre\/1968","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cityhub.com.sg\/ko\/wp-json\/wp\/v2\/centre"}],"about":[{"href":"https:\/\/www.cityhub.com.sg\/ko\/wp-json\/wp\/v2\/types\/centre"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cityhub.com.sg\/ko\/wp-json\/wp\/v2\/media\/1962"}],"wp:attachment":[{"href":"https:\/\/www.cityhub.com.sg\/ko\/wp-json\/wp\/v2\/media?parent=1968"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}